{"id":9549,"date":"2025-08-30T05:33:54","date_gmt":"2025-08-30T05:33:54","guid":{"rendered":"https:\/\/www.sgtgroup.net\/?page_id=9549"},"modified":"2025-12-16T08:35:54","modified_gmt":"2025-12-16T08:35:54","slug":"sostenibilidad-higg-fem-formacion-en-linea","status":"publish","type":"post","link":"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/","title":{"rendered":"Taller FEM de Higg"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9549\" class=\"elementor elementor-9549\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddae85f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddae85f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cb777b\" data-id=\"4cb777b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32adc57 elementor-widget elementor-widget-heading\" data-id=\"32adc57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">EXPERTOS DE SGT &amp; API <br> TALLER HIGG FEM 4.0\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-221a90c elementor-widget elementor-widget-heading\" data-id=\"221a90c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 DE OCTUBRE DE 2025<br>7 NOV 2025<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53411353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53411353\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-703354ec\" data-id=\"703354ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0cba70 elementor-widget elementor-widget-heading\" data-id=\"e0cba70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Taller Higg FEM 4.0<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a17b0 elementor-widget elementor-widget-text-editor\" data-id=\"78a17b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p style=\"text-align: center;\">Acelere el rendimiento sostenible de sus instalaciones con el taller pr\u00e1ctico Higg FEM 4.0 de SgT &amp; API. Dise\u00f1ado para los directores de f\u00e1brica, proveedores, esta sesi\u00f3n en l\u00ednea en vivo le muestra exactamente c\u00f3mo preparar los datos, completar la autoevaluaci\u00f3n, y aprovechar los resultados para impulsar mejoras y valor empresarial.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc2be76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc2be76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db22d0d\" data-id=\"db22d0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19b414c elementor-widget elementor-widget-heading\" data-id=\"19b414c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">A qui\u00e9n va dirigido:<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e07d952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e07d952\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fc3455\" data-id=\"9fc3455\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4503396 elementor-widget elementor-widget-text-editor\" data-id=\"4503396\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li style=\"line-height: 1.7;\"><span style=\"font-weight: bold;\">Directores de f\u00e1brica y responsables de sostenibilidad<\/span>: para mejorar los resultados medioambientales<\/li><li><span style=\"font-weight: bold;\">Proveedores:<\/span>\u00a0crear capacidad interna para satisfacer las necesidades de los clientes<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f251042 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f251042\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-869b04c\" data-id=\"869b04c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3de3b3e elementor-widget elementor-widget-heading\" data-id=\"3de3b3e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Calendario de talleres\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20b9645 elementor-widget elementor-widget-text-editor\" data-id=\"20b9645\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: left;\">Este plan de aprendizaje est\u00e1 dise\u00f1ado para proporcionar los conocimientos t\u00e9cnicos necesarios y las habilidades espec\u00edficas para Higg FEM 4.0. La sesi\u00f3n consta de los siguientes cursos:<\/p><p style=\"word-break: break-word; overflow-wrap: break-word; border: none; line-height: 1.7;\"><span style=\"padding: 0px; margin: 0px; -webkit-font-smoothing: antialiased; word-break: break-word; overflow-wrap: break-word; font-weight: bold;\">D\u00eda:<\/span>\u00a03 de octubre de 2025<br style=\"padding: 0px; margin: 0px; -webkit-font-smoothing: antialiased; word-break: break-word; overflow-wrap: break-word;\" \/><span style=\"padding: 0px; margin: 0px; -webkit-font-smoothing: antialiased; word-break: break-word; overflow-wrap: break-word; font-weight: bold;\">Hora:<\/span>\u00a0Pek\u00edn 10:00 \/ Dacca 8:00 \/ Nueva Delhi 07:30 \/ Ho Chi Minh 9:00<\/p><p style=\"word-break: break-word; overflow-wrap: break-word; border: none; line-height: 1.7;\">O<\/p><p><strong>D\u00eda:<\/strong> 7 de noviembre de 2025<br \/><strong>Hora:<\/strong> Pek\u00edn 11:00 \/ Dacca 9:00 \/ Nueva Delhi 08:30 \/ Ho Chi Minh 10:00<\/p><p><b>Duraci\u00f3n: <\/b>8 horas en directo en l\u00ednea (incluye presentaciones, preguntas y respuestas, y debate interactivo)<\/p><p><span style=\"font-weight: bold;\">Formato:\u00a0<\/span>Taller virtual a trav\u00e9s de Teams (El enlace se enviar\u00e1 tras la confirmaci\u00f3n del pago )<\/p><p style=\"line-height: 1.7;\"><span style=\"font-weight: bold;\">Tasa:\u00a0<\/span>USD$125 por participante (Incluye un certificado emitido por Cascale al finalizar) Pago con tarjetas de cr\u00e9dito en la p\u00e1gina de inscripci\u00f3n.<\/p><p><em>Descuento de 20% por inscripci\u00f3n anticipada antes del 26 de septiembre de 2025. ( Auto-aplicado en la caja )<\/em><\/p><p><em>\u00a0<\/em><\/p><p style=\"line-height: 1.7; text-align: center;\"><b>Las plazas son limitadas, \u00a1INSCR\u00cdBETE YA!<\/b><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce93309 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce93309\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.sgtgroup.net\/es\/contacto-taller-de-alta-fem\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Reg\u00edstrese ahora<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d693488 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d693488\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5a56b6\" data-id=\"d5a56b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a53fb0 elementor-widget elementor-widget-heading\" data-id=\"4a53fb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Lo que aprender\u00e1 (alineado con los temas de Higg FEM 4.0 de Cascale)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-564143a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"564143a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd6d48d\" data-id=\"bd6d48d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f01b860 elementor-widget elementor-widget-text-editor\" data-id=\"f01b860\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n \t<li style=\"text-align: left;\"><b>Introducci\u00f3n al MEF de Higg:\u00a0<\/b>Comprender el ciclo MEF de Higg, las herramientas de la plataforma y c\u00f3mo evitar errores comunes.<\/li>\n \t<li style=\"text-align: left;\"><b>Energ\u00eda, agua y residuos:\u00a0<\/b>Aprenda los contenidos de los niveles 1 a 3, c\u00f3mo establecer l\u00edneas de base y objetivos, realizar auditor\u00edas y garantizar la mejora continua.<\/li>\n \t<li><b>Sistema de Gesti\u00f3n Medioambiental y Gesti\u00f3n Qu\u00edmica:\u00a0<\/b>Explore las pol\u00edticas medioambientales, las evaluaciones de impacto, la gesti\u00f3n del riesgo qu\u00edmico, el almacenamiento y la trazabilidad.<\/li>\n \t<li style=\"text-align: left;\"><span style=\"font-weight: bold;\">Aguas residuales, aire y buenas pr\u00e1cticas:\u00a0<\/span>Descubra los par\u00e1metros de supervisi\u00f3n, los m\u00e9todos de control, las tecnolog\u00edas avanzadas y las mejores pr\u00e1cticas del sector.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7334dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7334dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-caff053\" data-id=\"caff053\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-815efd5 elementor-widget elementor-widget-heading\" data-id=\"815efd5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Agenda<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da0bc32 elementor-widget elementor-widget-text-editor\" data-id=\"da0bc32\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b>Sesi\u00f3n 1 : <\/b>Bienvenida y orientaci\u00f3n: Qu\u00e9 es el MEF de Higg y por qu\u00e9 es importante 4.0<\/p>\n<p><b>Sesi\u00f3n 2 : <\/b>Marco y puntuaci\u00f3n: Estructura, puntuaci\u00f3n y actualizaciones clave de la 4.0 frente a la 3.0<\/p>\n<p><b>Sesi\u00f3n 3 : <\/b>Profundizaci\u00f3n en las secciones de impacto: Energ\u00eda\/GHG, agua, aguas residuales, emisiones a la atm\u00f3sfera, residuos, productos qu\u00edmicos, EMS Break<\/p>\n<p><b>Sesi\u00f3n 4 : <\/b>Datos y pruebas: Qu\u00e9 recopilar, fuentes y mejores pr\u00e1cticas de registro<\/p>\n<p><b>Sesi\u00f3n 5 : <\/b>De la autoevaluaci\u00f3n a la verificaci\u00f3n: Gu\u00eda paso a paso, plazos, errores comunes<\/p>\n<p><b>Sesi\u00f3n 6 : <\/b>Planificaci\u00f3n de mejoras, colaboraci\u00f3n entre proveedores y marcas, comunicaci\u00f3n de resultados<\/p>\n<p><b>Sesi\u00f3n 7 : <\/b>Preguntas y respuestas en directo y pr\u00f3ximos pasos<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-330d207 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"330d207\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8f7a5e\" data-id=\"d8f7a5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e19471 elementor-widget elementor-widget-heading\" data-id=\"4e19471\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Al final del taller, ser\u00e1s capaz de<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da7e78e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da7e78e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0912400\" data-id=\"0912400\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-188b8e5 elementor-widget elementor-widget-text-editor\" data-id=\"188b8e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div style=\"display: flex; justify-content: left;\"><ul style=\"padding-left: 50px;\"><li>Elaborar un plan de recogida de datos a nivel de centro adaptado a Higg FEM 4.0<\/li><li>Completar con confianza la autoevaluaci\u00f3n de Higg FEM 4.0 y prepararse para la verificaci\u00f3n.<\/li><li>Utilizar los resultados de Higg FEM 4.0 para priorizar las mejoras y comprometer a marcas y minoristas.<\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-991f7c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"991f7c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b2960c\" data-id=\"4b2960c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f81e43 elementor-widget elementor-widget-heading\" data-id=\"9f81e43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Por qu\u00e9 SgT y API<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-728bb1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"728bb1f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84a7aad\" data-id=\"84a7aad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba226d3 elementor-widget elementor-widget-text-editor\" data-id=\"ba226d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul style=\"padding-left: 50px; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\"><li><span style=\"font-weight: bold;\">Organismo de formaci\u00f3n verificado:<\/span>\u00a0SgT y API est\u00e1n cualificados para impartir formaci\u00f3n sobre HIGG FEM 4.0.<\/li><li><span style=\"font-weight: bold;\">Pr\u00e1ctico y pr\u00e1ctico:<\/span>\u00a0Ejemplos de instalaciones reales, listas de comprobaci\u00f3n y plantillas que puede utilizar inmediatamente.<\/li><li><span style=\"font-weight: bold;\">Formadores expertos:<\/span>\u00a0Dirigido por experimentados profesionales de la sostenibilidad con profundos conocimientos sobre el \u00cdndice de Higg.<\/li><li><span style=\"font-weight: bold;\">Aprendizaje interactivo:<\/span>\u00a0Preguntas y respuestas en directo e intercambio entre compa\u00f1eros para abordar sus retos espec\u00edficos.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5b4cf1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5b4cf1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-062803a\" data-id=\"062803a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-515afa6 elementor-widget elementor-widget-image\" data-id=\"515afa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"109\" src=\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png 300w, https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-18x7.png 18w, https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1.png 609w\" sizes=\"(max-width: 300px) 100vw, 300px\" style=\"width:100%;height:36.29%;max-width:609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38e962d elementor-widget elementor-widget-text-editor\" data-id=\"38e962d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Las plazas son limitadas. Reserve su plaza ahora y prepare sus instalaciones para Higg FEM 4.0.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e871278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e871278\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24cf0a8\" data-id=\"24cf0a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2c1efd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b2c1efd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.sgtgroup.net\/es\/contacto-taller-de-alta-fem\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Reg\u00edstrese ahora<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3590886 elementor-widget elementor-widget-text-editor\" data-id=\"3590886\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b>Pol\u00edtica de pago y cancelaci\u00f3n:<\/b><\/p><ul><li><b>Pago e inscripci\u00f3n<\/b><\/li><li>Todos los pagos se procesan de forma segura a trav\u00e9s de Stripe. Nosotros <b>no almacenar<\/b> los datos de su tarjeta de cr\u00e9dito.<\/li><li>Tras completar su inscripci\u00f3n, recibir\u00e1:<ul><li><b>Un recibo de pago<\/b><\/li><li><b>En<\/b> <b>confirmaci\u00f3n del evento<\/b><\/li><\/ul><\/li><li>Se le enviar\u00e1 el enlace de la reuni\u00f3n del taller <b>dos semanas antes del taller<\/b>junto con un correo electr\u00f3nico recordatorio dos d\u00edas <b>anterior<\/b> al acontecimiento.<\/li><li>Tenga en cuenta que los pagos se gestionar\u00e1n bajo el nombre de ADVANCED QUALITY FOCUS. Es posible que vea ADVANCED QUALITY FOCUS en su recibo o en el extracto de la transacci\u00f3n.<\/li><\/ul><p><b style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Pol\u00edtica de cancelaci\u00f3n y reembolso<\/b><\/p><ul><li>Puede cancelar su inscripci\u00f3n hasta 7 d\u00edas laborables antes del evento; en este caso, recibir\u00e1 un reembolso completo.<\/li><li>En caso de anulaci\u00f3n con menos de 7 d\u00edas laborables de antelaci\u00f3n, se reembolsar\u00e1 el 50% de la tasa.<\/li><\/ul><p><b>El Grupo SgT se reserva el derecho a tomar las decisiones finales sobre todos los aspectos del taller.<\/b><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>SGT &amp; API\u2019S EXPERT-LED HIGG FEM 4.0 WORKSHOP 3 OCT 2025 7 NOV 2025 Higg FEM 4.0 Workshop Accelerate your facility\u2019s sustainability performance with SgT &amp; API\u2019s practical Higg FEM 4.0 workshop. Designed for factory managers, suppliers, this live online session shows you exactly how to prepare the data, complete the self-assessment, and leverage results&hellip; <a class=\"more-link\" href=\"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/\">Seguir leyendo <span class=\"screen-reader-text\">Taller FEM de Higg<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-9549","post","type-post","status-publish","format-standard","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.5 (Yoast SEO v22.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Higg FEM Workshop - SgT, The Textile Quality Experts<\/title>\n<meta name=\"description\" content=\"Join our Higg index workshop to enhance your facility\u2019s sustainability performance through interactive learning and expert guidance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Higg FEM Workshop\" \/>\n<meta property=\"og:description\" content=\"Join our Higg index workshop to enhance your facility\u2019s sustainability performance through interactive learning and expert guidance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/\" \/>\n<meta property=\"og:site_name\" content=\"SgT, The Textile Quality Experts\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-30T05:33:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T08:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\" \/>\n<meta name=\"author\" content=\"Admin SgT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin SgT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/\"},\"author\":{\"name\":\"Admin SgT\",\"@id\":\"https:\/\/www.sgtgroup.net\/#\/schema\/person\/3a80ac3a5558711e27d3595da56eceba\"},\"headline\":\"Higg FEM Workshop\",\"datePublished\":\"2025-08-30T05:33:54+00:00\",\"dateModified\":\"2025-12-16T08:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\/\/www.sgtgroup.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/\",\"url\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/\",\"name\":\"Higg FEM Workshop - SgT, The Textile Quality Experts\",\"isPartOf\":{\"@id\":\"https:\/\/www.sgtgroup.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\",\"datePublished\":\"2025-08-30T05:33:54+00:00\",\"dateModified\":\"2025-12-16T08:35:54+00:00\",\"description\":\"Join our Higg index workshop to enhance your facility\u2019s sustainability performance through interactive learning and expert guidance.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage\",\"url\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\",\"contentUrl\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sgtgroup.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Higg FEM Workshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sgtgroup.net\/#website\",\"url\":\"https:\/\/www.sgtgroup.net\/\",\"name\":\"SgT, The Textile Quality Experts\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sgtgroup.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sgtgroup.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sgtgroup.net\/#organization\",\"name\":\"SgT, The Textile Quality Experts\",\"url\":\"https:\/\/www.sgtgroup.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.sgtgroup.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2022\/03\/logo_sgt.png\",\"contentUrl\":\"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2022\/03\/logo_sgt.png\",\"width\":208,\"height\":194,\"caption\":\"SgT, The Textile Quality Experts\"},\"image\":{\"@id\":\"https:\/\/www.sgtgroup.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/youtube.com\/@sgtgroup4075\",\"https:\/\/www.linkedin.com\/company\/sgt-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sgtgroup.net\/#\/schema\/person\/3a80ac3a5558711e27d3595da56eceba\",\"name\":\"Admin SgT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.sgtgroup.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/84495daea39f8d93141e3b6b61b6205caed07122306c203fbf2e998af076b59e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/84495daea39f8d93141e3b6b61b6205caed07122306c203fbf2e998af076b59e?s=96&d=mm&r=g\",\"caption\":\"Admin SgT\"},\"sameAs\":[\"http:\/\/206.221.182.74\/~getgo163\/SGT\"],\"url\":\"https:\/\/www.sgtgroup.net\/es\/author\/admin_sgt\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Taller FEM de Higg - SgT, Los Expertos en Calidad Textil","description":"Participe en nuestro taller sobre el \u00edndice Higg para mejorar el rendimiento sostenible de sus instalaciones mediante un aprendizaje interactivo y la orientaci\u00f3n de expertos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/","og_locale":"es_ES","og_type":"article","og_title":"Higg FEM Workshop","og_description":"Join our Higg index workshop to enhance your facility\u2019s sustainability performance through interactive learning and expert guidance.","og_url":"https:\/\/www.sgtgroup.net\/es\/sostenibilidad-higg-fem-formacion-en-linea\/","og_site_name":"SgT, The Textile Quality Experts","article_published_time":"2025-08-30T05:33:54+00:00","article_modified_time":"2025-12-16T08:35:54+00:00","og_image":[{"url":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png"}],"author":"Admin SgT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Admin SgT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#article","isPartOf":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/"},"author":{"name":"Admin SgT","@id":"https:\/\/www.sgtgroup.net\/#\/schema\/person\/3a80ac3a5558711e27d3595da56eceba"},"headline":"Higg FEM Workshop","datePublished":"2025-08-30T05:33:54+00:00","dateModified":"2025-12-16T08:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/"},"wordCount":611,"publisher":{"@id":"https:\/\/www.sgtgroup.net\/#organization"},"image":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/","url":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/","name":"Taller FEM de Higg - SgT, Los Expertos en Calidad Textil","isPartOf":{"@id":"https:\/\/www.sgtgroup.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage"},"image":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png","datePublished":"2025-08-30T05:33:54+00:00","dateModified":"2025-12-16T08:35:54+00:00","description":"Participe en nuestro taller sobre el \u00edndice Higg para mejorar el rendimiento sostenible de sus instalaciones mediante un aprendizaje interactivo y la orientaci\u00f3n de expertos.","breadcrumb":{"@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#primaryimage","url":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png","contentUrl":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2025\/09\/Logo-FEM-Trainer-Body-1-300x109.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sgtgroup.net\/sustainability-higg-fem-online-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sgtgroup.net\/"},{"@type":"ListItem","position":2,"name":"Higg FEM Workshop"}]},{"@type":"WebSite","@id":"https:\/\/www.sgtgroup.net\/#website","url":"https:\/\/www.sgtgroup.net\/","name":"SgT, los expertos en calidad textil","description":"","publisher":{"@id":"https:\/\/www.sgtgroup.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sgtgroup.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sgtgroup.net\/#organization","name":"SgT, los expertos en calidad textil","url":"https:\/\/www.sgtgroup.net\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sgtgroup.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2022\/03\/logo_sgt.png","contentUrl":"https:\/\/www.sgtgroup.net\/wp-content\/uploads\/2022\/03\/logo_sgt.png","width":208,"height":194,"caption":"SgT, The Textile Quality Experts"},"image":{"@id":"https:\/\/www.sgtgroup.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/youtube.com\/@sgtgroup4075","https:\/\/www.linkedin.com\/company\/sgt-group"]},{"@type":"Person","@id":"https:\/\/www.sgtgroup.net\/#\/schema\/person\/3a80ac3a5558711e27d3595da56eceba","name":"Admin SgT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sgtgroup.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/84495daea39f8d93141e3b6b61b6205caed07122306c203fbf2e998af076b59e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84495daea39f8d93141e3b6b61b6205caed07122306c203fbf2e998af076b59e?s=96&d=mm&r=g","caption":"Admin SgT"},"sameAs":["http:\/\/206.221.182.74\/~getgo163\/SGT"],"url":"https:\/\/www.sgtgroup.net\/es\/author\/admin_sgt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/posts\/9549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/comments?post=9549"}],"version-history":[{"count":0,"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/posts\/9549\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/media?parent=9549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/categories?post=9549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sgtgroup.net\/es\/wp-json\/wp\/v2\/tags?post=9549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}